{"id":4096,"date":"2024-02-15T05:12:37","date_gmt":"2024-02-15T13:12:37","guid":{"rendered":"https:\/\/abacourses.com\/product\/pecs\/"},"modified":"2024-02-15T05:12:37","modified_gmt":"2024-02-15T13:12:37","slug":"pecs","status":"publish","type":"product","link":"https:\/\/abacourses.com\/es\/producto\/pecs\/","title":{"rendered":"PECS"},"content":{"rendered":"<p>Pasos para PECS, para que puedas implementarlo en tus sesiones de ABA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pasos para PECS, para que puedas implementarlo en tus sesiones de ABA.<\/p>\n","protected":false},"featured_media":3498,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[444],"product_tag":[],"class_list":{"0":"post-4096","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cursos","8":"first","9":"instock","10":"downloadable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PECS - ABA Courses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abacourses.com\/es\/producto\/pecs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PECS - ABA Courses\" \/>\n<meta property=\"og:description\" content=\"Pasos para PECS, para que puedas implementarlo en tus sesiones de ABA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abacourses.com\/es\/producto\/pecs\/\" \/>\n<meta property=\"og:site_name\" content=\"ABA Courses\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abacourses.com\/wp-content\/uploads\/2021\/02\/pexels-yan-krukau-8613091.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/\",\"url\":\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/\",\"name\":\"PECS - ABA Courses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abacourses.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abacourses.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/pexels-yan-krukau-8613091.jpg\",\"datePublished\":\"2024-02-15T13:12:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/abacourses.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/pexels-yan-krukau-8613091.jpg\",\"contentUrl\":\"https:\\\/\\\/abacourses.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/pexels-yan-krukau-8613091.jpg\",\"width\":640,\"height\":960,\"caption\":\"ABA session\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abacourses.com\\\/es\\\/producto\\\/pecs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/abacourses.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comercio\",\"item\":\"https:\\\/\\\/abacourses.com\\\/es\\\/comercio-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PECS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abacourses.com\\\/#website\",\"url\":\"https:\\\/\\\/abacourses.com\\\/\",\"name\":\"ABA Courses\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/abacourses.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abacourses.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abacourses.com\\\/#organization\",\"name\":\"ABA courses\",\"url\":\"https:\\\/\\\/abacourses.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/abacourses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abacourses.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Logo_ABA-Courses_square.jpg?time=1704898546\",\"contentUrl\":\"https:\\\/\\\/abacourses.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Logo_ABA-Courses_square.jpg?time=1704898546\",\"width\":300,\"height\":300,\"caption\":\"ABA courses\"},\"image\":{\"@id\":\"https:\\\/\\\/abacourses.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PECS - ABA Courses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abacourses.com\/es\/producto\/pecs\/","og_locale":"es_ES","og_type":"article","og_title":"PECS - ABA Courses","og_description":"Pasos para PECS, para que puedas implementarlo en tus sesiones de ABA.","og_url":"https:\/\/abacourses.com\/es\/producto\/pecs\/","og_site_name":"ABA Courses","og_image":[{"width":640,"height":960,"url":"https:\/\/abacourses.com\/wp-content\/uploads\/2021\/02\/pexels-yan-krukau-8613091.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/abacourses.com\/es\/producto\/pecs\/","url":"https:\/\/abacourses.com\/es\/producto\/pecs\/","name":"PECS - ABA Courses","isPartOf":{"@id":"https:\/\/abacourses.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abacourses.com\/es\/producto\/pecs\/#primaryimage"},"image":{"@id":"https:\/\/abacourses.com\/es\/producto\/pecs\/#primaryimage"},"thumbnailUrl":"https:\/\/abacourses.com\/wp-content\/uploads\/2021\/02\/pexels-yan-krukau-8613091.jpg","datePublished":"2024-02-15T13:12:37+00:00","breadcrumb":{"@id":"https:\/\/abacourses.com\/es\/producto\/pecs\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abacourses.com\/es\/producto\/pecs\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/abacourses.com\/es\/producto\/pecs\/#primaryimage","url":"https:\/\/abacourses.com\/wp-content\/uploads\/2021\/02\/pexels-yan-krukau-8613091.jpg","contentUrl":"https:\/\/abacourses.com\/wp-content\/uploads\/2021\/02\/pexels-yan-krukau-8613091.jpg","width":640,"height":960,"caption":"ABA session"},{"@type":"BreadcrumbList","@id":"https:\/\/abacourses.com\/es\/producto\/pecs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abacourses.com\/es\/"},{"@type":"ListItem","position":2,"name":"Comercio","item":"https:\/\/abacourses.com\/es\/comercio-2\/"},{"@type":"ListItem","position":3,"name":"PECS"}]},{"@type":"WebSite","@id":"https:\/\/abacourses.com\/#website","url":"https:\/\/abacourses.com\/","name":"ABA Courses","description":"","publisher":{"@id":"https:\/\/abacourses.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abacourses.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/abacourses.com\/#organization","name":"ABA courses","url":"https:\/\/abacourses.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/abacourses.com\/#\/schema\/logo\/image\/","url":"https:\/\/abacourses.com\/wp-content\/uploads\/2022\/09\/Logo_ABA-Courses_square.jpg?time=1704898546","contentUrl":"https:\/\/abacourses.com\/wp-content\/uploads\/2022\/09\/Logo_ABA-Courses_square.jpg?time=1704898546","width":300,"height":300,"caption":"ABA courses"},"image":{"@id":"https:\/\/abacourses.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/product\/4096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/media\/3498"}],"wp:attachment":[{"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/media?parent=4096"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/product_brand?post=4096"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/product_cat?post=4096"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/abacourses.com\/es\/wp-json\/wp\/v2\/product_tag?post=4096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}